{"id":2996,"date":"2026-02-20T09:37:54","date_gmt":"2026-02-20T09:37:54","guid":{"rendered":"https:\/\/lesclesdeprovence.com\/?post_type=product&#038;p=2996"},"modified":"2026-05-15T04:22:17","modified_gmt":"2026-05-15T04:22:17","slug":"navette-gare-aix-tgv","status":"publish","type":"product","link":"https:\/\/lesclesdeprovence.com\/en\/product\/navette-gare-aix-tgv\/","title":{"rendered":"Aix TGV Station Shuttle"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Vous n&rsquo;avez pas besoin d&rsquo;un v\u00e9hicule pour toute la semaine ? Nous assurons votre transfert en toute s\u00e9r\u00e9nit\u00e9, depuis les principaux a\u00e9roports et gares de la r\u00e9gion jusqu&rsquo;\u00e0 votre villa \u00e0 Cotignac, dans le Var.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Votre s\u00e9jour en Provence commence d\u00e8s la descente de l&rsquo;avion ou du train, sans stress ni attente.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">R\u00e9servez votre navette aller, retour, ou les deux selon vos besoins.<\/p>\n<p><em><strong>Photo non contractuelle<\/strong><\/em><\/p>\n","protected":false},"featured_media":4249,"template":"","meta":[],"product_brand":[],"product_cat":[15],"product_tag":[],"class_list":["post-2996","product","type-product","status-publish","has-post-thumbnail","product_cat-uncategorized","first","instock","sold-individually","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/lesclesdeprovence.com\/en\/wp-json\/wp\/v2\/product\/2996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesclesdeprovence.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lesclesdeprovence.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lesclesdeprovence.com\/en\/wp-json\/wp\/v2\/media\/4249"}],"wp:attachment":[{"href":"https:\/\/lesclesdeprovence.com\/en\/wp-json\/wp\/v2\/media?parent=2996"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lesclesdeprovence.com\/en\/wp-json\/wp\/v2\/product_brand?post=2996"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lesclesdeprovence.com\/en\/wp-json\/wp\/v2\/product_cat?post=2996"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lesclesdeprovence.com\/en\/wp-json\/wp\/v2\/product_tag?post=2996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}